{"id":1262,"date":"2020-06-01T12:46:41","date_gmt":"2020-06-01T10:46:41","guid":{"rendered":"http:\/\/biosedev.com\/?p=1262"},"modified":"2020-06-01T12:46:42","modified_gmt":"2020-06-01T10:46:42","slug":"on-parle-de-biosede-dans-le-magazine-formule-verte","status":"publish","type":"post","link":"https:\/\/biosedev.com\/index.php\/2020\/06\/01\/on-parle-de-biosede-dans-le-magazine-formule-verte\/","title":{"rendered":"On parle de BioseDe dans le Magazine Formule Verte"},"content":{"rendered":"<p>Tr\u00e8s belle mise en avant de BioseDev dans le magazine de la chimie du v\u00e9g\u00e9tal #FormuleVerte n\u00b043 d&#8217;avril 2020, volet \u00e9conomie circulaire.<\/p>\n<p>Merci \u00e0 M.Dinhill On, Chef de rubrique Chimie et Proc\u00e9d\u00e9s \u00e0 Formule Verte pour ce superbe article.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00e8s belle mise en avant de BioseDev dans le magazine de la chimie du v\u00e9g\u00e9tal #FormuleVerte n\u00b043 d&#8217;avril 2020, volet \u00e9conomie circulaire. Merci \u00e0 M.Dinhill On, Chef de rubrique Chimie et Proc\u00e9d\u00e9s \u00e0 Formule Verte pour ce superbe article.<\/p>\n","protected":false},"author":1,"featured_media":1264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/posts\/1262"}],"collection":[{"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/comments?post=1262"}],"version-history":[{"count":1,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/posts\/1262\/revisions"}],"predecessor-version":[{"id":1265,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/posts\/1262\/revisions\/1265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/media\/1264"}],"wp:attachment":[{"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/media?parent=1262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/categories?post=1262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biosedev.com\/index.php\/wp-json\/wp\/v2\/tags?post=1262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}